{"id":608,"count":1,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ar\/tag\/cylinder-frame\/","name":"cylinder frame","slug":"cylinder-frame","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ar\/wp-json\/wp\/v2\/tags\/608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ar\/wp-json\/wp\/v2\/posts?tags=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}