{"id":373,"count":7,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/de\/tag\/lock-cylinder\/","name":"lock cylinder","slug":"lock-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/de\/wp-json\/wp\/v2\/tags\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/de\/wp-json\/wp\/v2\/posts?tags=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}