{"id":488,"count":3,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/fa\/tag\/cylinder-argon\/","name":"cylinder argon","slug":"cylinder-argon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fa\/wp-json\/wp\/v2\/tags\/488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fa\/wp-json\/wp\/v2\/posts?tags=488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}