{"id":393,"count":7,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/fr\/tag\/seamless-cylinder\/","name":"seamless cylinder","slug":"seamless-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fr\/wp-json\/wp\/v2\/tags\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/fr\/wp-json\/wp\/v2\/posts?tags=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}