{"id":477,"count":3,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/tag\/argon-cylinder\/","name":"argon cylinder","slug":"argon-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/tags\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/posts?tags=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}