{"id":513,"count":6,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/tag\/10l-oxygen-cylinder\/","name":"10l oxygen cylinder","slug":"10l-oxygen-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/tags\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/hi\/wp-json\/wp\/v2\/posts?tags=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}