{"id":153,"count":4,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/tag\/hydraulic-cylinder-press\/","name":"hydraulic cylinder press","slug":"hydraulic-cylinder-press","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/tags\/153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/posts?tags=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}