{"id":386,"count":5,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/tag\/small-cylinder-single-acting\/","name":"small cylinder single acting","slug":"small-cylinder-single-acting","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/tags\/386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/posts?tags=386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}