{"id":675,"count":1,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/tag\/alloy-cylinder\/","name":"alloy cylinder","slug":"alloy-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/tags\/675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/it\/wp-json\/wp\/v2\/posts?tags=675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}