{"id":10,"count":129,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ja\/tag\/hydraulic-cylinder-pump\/","name":"hydraulic cylinder pump","slug":"hydraulic-cylinder-pump","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ja\/wp-json\/wp\/v2\/tags\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ja\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ja\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ja\/wp-json\/wp\/v2\/posts?tags=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}