{"id":285,"count":8,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/tag\/small-hydraulic-cylinder\/","name":"small hydraulic cylinder","slug":"small-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/tags\/285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/posts?tags=285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}