{"id":482,"count":3,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/tag\/co2-argon-cylinder\/","name":"co2 argon cylinder","slug":"co2-argon-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/tags\/482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/kk\/wp-json\/wp\/v2\/posts?tags=482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}