{"id":630,"count":2,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ko\/tag\/0-6l-cylinder\/","name":"0.6l cylinder","slug":"0-6l-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ko\/wp-json\/wp\/v2\/tags\/630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ko\/wp-json\/wp\/v2\/posts?tags=630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}