{"id":281,"count":8,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/tag\/hydraulic-cylinder-small\/","name":"hydraulic cylinder small","slug":"hydraulic-cylinder-small","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/tags\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/posts?tags=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}