{"id":384,"count":12,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/tag\/cylinder-oxygen\/","name":"cylinder oxygen","slug":"cylinder-oxygen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/tags\/384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/posts?tags=384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}