{"id":408,"count":1,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/tag\/roller-tractor\/","name":"roller tractor","slug":"roller-tractor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/tags\/408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nl\/wp-json\/wp\/v2\/posts?tags=408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}