{"id":171,"count":10,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/tag\/mini-cylinder\/","name":"mini cylinder","slug":"mini-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/tags\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/posts?tags=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}