{"id":174,"count":3,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/tag\/mini-hydraulic-excavator\/","name":"mini hydraulic excavator","slug":"mini-hydraulic-excavator","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/tags\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/nn\/wp-json\/wp\/v2\/posts?tags=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}