{"id":196,"count":8,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/tag\/tipper-hydraulic-cylinder\/","name":"tipper hydraulic cylinder","slug":"tipper-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/tags\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/posts?tags=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}