{"id":204,"count":7,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/tag\/hydraulic-hollow-cylinder\/","name":"hydraulic hollow cylinder","slug":"hydraulic-hollow-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/tags\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/pl\/wp-json\/wp\/v2\/posts?tags=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}