{"id":3,"count":207,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/tag\/china-hydraulic-cylinder\/","name":"china hydraulic cylinder","slug":"china-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/tags\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/posts?tags=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}