{"id":677,"count":1,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/tag\/aluminum-hydraulic-cylinder\/","name":"aluminum hydraulic cylinder","slug":"aluminum-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/tags\/677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ru\/wp-json\/wp\/v2\/posts?tags=677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}