{"id":132,"count":7,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ta\/tag\/arm-cylinder\/","name":"arm cylinder","slug":"arm-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ta\/wp-json\/wp\/v2\/tags\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ta\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ta\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ta\/wp-json\/wp\/v2\/posts?tags=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}