{"id":573,"count":2,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/tr\/tag\/cylinder-valve\/","name":"cylinder valve","slug":"cylinder-valve","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/tr\/wp-json\/wp\/v2\/tags\/573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/tr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/tr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/tr\/wp-json\/wp\/v2\/posts?tags=573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}