{"id":526,"count":6,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/uk\/tag\/china-medical-oxygen-cylinder\/","name":"china medical oxygen cylinder","slug":"china-medical-oxygen-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/uk\/wp-json\/wp\/v2\/tags\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/uk\/wp-json\/wp\/v2\/posts?tags=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}