{"id":126,"count":10,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/tag\/lift-cylinder\/","name":"lift cylinder","slug":"lift-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/tags\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/posts?tags=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}