{"id":610,"count":1,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/tag\/cylinder-2l\/","name":"cylinder 2l","slug":"cylinder-2l","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/tags\/610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/ur\/wp-json\/wp\/v2\/posts?tags=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}