{"id":49,"count":57,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/tag\/telescopic-hydraulic-cylinder\/","name":"telescopic hydraulic cylinder","slug":"telescopic-hydraulic-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/tags\/49","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/posts?tags=49"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}