{"id":530,"count":6,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/tag\/medical-cylinder\/","name":"medical cylinder","slug":"medical-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/tags\/530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/posts?tags=530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}