{"id":670,"count":1,"description":"","link":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/tag\/2-cylinder\/","name":"2 cylinder","slug":"2-cylinder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/tags\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/single-acting-hydraulic-cylinder.com\/vi\/wp-json\/wp\/v2\/posts?tags=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}